{"id":4752,"date":"2020-07-16T10:10:58","date_gmt":"2020-07-16T14:10:58","guid":{"rendered":"https:\/\/tourisme-memphremagog.com\/fiches\/au-fou-du-roi\/"},"modified":"2025-03-13T10:46:14","modified_gmt":"2025-03-13T14:46:14","slug":"au-fou-du-roi","status":"publish","type":"fiche","link":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/","title":{"rendered":"Au Fou du Roi"},"template":"","class_list":["post-4752","fiche","type-fiche","status-publish","hentry"],"acf":{"fiche_municipalite":"magog","relation_principale":[915],"relation_secondaire":[920],"relation_thematique":[2493],"relation_typevoyage":[1170,1174,1171,1172,1173,1168],"relation_promo":"","fiche_saison":["Hiver","Printemps","\u00c9t\u00e9","Automne"],"relation_categories":[1804,1877,1862,1818,1808,2806],"classification_filtres":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au Fou du Roi - Tourisme Memphremagog<\/title>\n<meta name=\"description\" content=\"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au Fou du Roi - Tourisme Memphremagog\" \/>\n<meta property=\"og:description\" content=\"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourisme Memphremagog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TourismeMemphre\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T14:46:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/au-fou-du-roi\\\/\",\"url\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/au-fou-du-roi\\\/\",\"name\":\"Au Fou du Roi - Tourisme Memphremagog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/#website\"},\"datePublished\":\"2020-07-16T14:10:58+00:00\",\"dateModified\":\"2025-03-13T14:46:14+00:00\",\"description\":\"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/au-fou-du-roi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/au-fou-du-roi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/au-fou-du-roi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiches\",\"item\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/fiches\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Au Fou du Roi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/\",\"name\":\"Tourisme Memphremagog\",\"description\":\"Vraiment belle de nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tourisme-memphremagog.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au Fou du Roi - Tourisme Memphremagog","description":"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/","og_locale":"en_US","og_type":"article","og_title":"Au Fou du Roi - Tourisme Memphremagog","og_description":"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships","og_url":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/","og_site_name":"Tourisme Memphremagog","article_publisher":"https:\/\/www.facebook.com\/TourismeMemphre\/","article_modified_time":"2025-03-13T14:46:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/","url":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/","name":"Au Fou du Roi - Tourisme Memphremagog","isPartOf":{"@id":"https:\/\/tourisme-memphremagog.com\/en\/#website"},"datePublished":"2020-07-16T14:10:58+00:00","dateModified":"2025-03-13T14:46:14+00:00","description":"Over 150 food choices available. Offers a variety of freshly prepared healthy and diverse dishes. Coffee, bread, meals. Eastern Townships","breadcrumb":{"@id":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/au-fou-du-roi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/tourisme-memphremagog.com\/en\/"},{"@type":"ListItem","position":2,"name":"Fiches","item":"https:\/\/tourisme-memphremagog.com\/en\/fiches\/"},{"@type":"ListItem","position":3,"name":"Au Fou du Roi"}]},{"@type":"WebSite","@id":"https:\/\/tourisme-memphremagog.com\/en\/#website","url":"https:\/\/tourisme-memphremagog.com\/en\/","name":"Tourisme Memphremagog","description":"Vraiment belle de nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourisme-memphremagog.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/fiche\/4752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/fiche"}],"about":[{"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/types\/fiche"}],"acf:post":[{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/2806"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/1808"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/1818"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/1862"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/1877"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/categories\/1804"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1168"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1173"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1172"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1171"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1174"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/typeactivite\/1170"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/thematique\/2493"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/pages\/920"},{"embeddable":true,"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/pages\/915"}],"wp:attachment":[{"href":"https:\/\/tourisme-memphremagog.com\/en\/wp-json\/wp\/v2\/media?parent=4752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}